{"id":3027,"count":0,"description":"","link":"http:\/\/www.shmoualsalamart.com\/blog\/tag\/smart-lock-4288-cd8793\/","name":"Smart Lock","slug":"smart-lock-4288-cd8793","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.shmoualsalamart.com\/blog\/wp-json\/wp\/v2\/tags\/3027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.shmoualsalamart.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.shmoualsalamart.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.shmoualsalamart.com\/blog\/wp-json\/wp\/v2\/posts?tags=3027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}